{"id":2265,"date":"2021-08-13T06:15:50","date_gmt":"2021-08-13T04:15:50","guid":{"rendered":"https:\/\/hove-as.com\/contacto\/"},"modified":"2022-09-25T18:06:38","modified_gmt":"2022-09-25T16:06:38","slug":"contato","status":"publish","type":"page","link":"https:\/\/hove-as.com\/pt-pt\/contato\/","title":{"rendered":"Contato"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-style-hero\" style=\"min-height:440px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-blue-1-background-color has-background-dim-0 has-background-dim\"><\/span><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-1096\" alt=\"\" src=\"https:\/\/hove-as.com\/wp-content\/uploads\/2022\/09\/hero-contact.png\" data-object-fit=\"cover\"\/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group alignwide has-white-color has-text-color\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h1 class=\"wp-block-heading\">Como podemos ajud\u00e1-lo a continuar?<\/h1>\n\n\n\n<p>Encontre o seu escrit\u00f3rio, revendedor ou parceiro de servi\u00e7o local<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n\n\n<div class=\"wp-block-group alignfull has-blue-1-color has-blue-3-background-color has-text-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group alignwide\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:65%\">\n<h2 class=\"has-blue-1-color has-text-color wp-block-heading\">Contacte-nos<\/h2>\n\n\n\n<p class=\"is-style-lead has-blue-1-color has-text-color\">Gratos pelo seu contacto! Por favor, forne\u00e7a as suas informa\u00e7\u00f5es e entraremos em contacto consigo.<br>Quanto mais soubermos sobre o seu pedido, mais f\u00e1cil \u00e9 p\u00f4-lo em contacto com a pessoa certa ou dar-lhe a informa\u00e7\u00e3o correta.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2315-o1\" lang=\"pt-PT\" dir=\"ltr\" data-wpcf7-id=\"2315\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt-pt\/wp-json\/wp\/v2\/pages\/2265#wpcf7-f2315-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2315\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_PT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2315-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:2315,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;repeater_remove_button&quot;:&quot;bottom&quot;,&quot;notice_dismissed_update-cf7-5.7.3&quot;:true}}\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-md-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome pr\u00f3prio*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"your-lastname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Apelido*\" value=\"\" type=\"text\" name=\"your-lastname\" \/><\/span><br \/>\n<span id=\"wpcf7-6a97e3e2d52e0-wrapper\" class=\"wpcf7-form-control-wrap website-wrap\" ><input type=\"hidden\" name=\"website-time-start\" value=\"1788339170\"><input type=\"hidden\" name=\"website-time-check\" value=\"7\"><label for=\"wpcf7-6a97e3e2d52e0-field\" class=\"hp-message\">Please leave this field empty.<\/label><input id=\"wpcf7-6a97e3e2d52e0-field\"  placeholder=\"http:\/\/example.com\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"website\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome da empresa*\" value=\"\" type=\"text\" name=\"your-company\" \/><\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"4\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Mensagem*\" name=\"your-message\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_source\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_medium\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_campaign\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_term\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_content\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_id\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"first_utm_source\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"first_utm_medium\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"first_utm_campaign\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"first_utm_term\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"first_utm_content\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"first_utm_id\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"gclid\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"gbraid\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"wbraid\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"gad_source\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"gclsrc\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"dclid\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"fbclid\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"msclkid\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"ms_network\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"li_fat_id\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"rdt_cid\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"ga_client_id\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"landing_page\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"first_landing_page\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"referrer\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"first_visit_timestamp\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"contact-us\" type=\"hidden\" name=\"form_name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"page_url\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"page_language\" \/>\n<div class=\"row\">\n\t<div class=\"col-md-4\">\n\t\t<div class=\"wp-block-buttons\">\n\t\t\t<div class=\"wp-block-button is-style-outline\">\n\t\t\t\t<p><label class=\"wp-block-button__link has-text-color has-blue-1-color\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/><\/label>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Contacte-nos Gratos pelo seu contacto! Por favor, forne\u00e7a as suas informa\u00e7\u00f5es e entraremos em contacto consigo.Quanto mais soubermos sobre o seu pedido, mais f\u00e1cil \u00e9 p\u00f4-lo em contacto com a pessoa certa ou dar-lhe a informa\u00e7\u00e3o correta.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":35,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"class_list":["post-2265","page","type-page","status-publish","hentry","entry"],"acf":{"color":"blue-1"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contato - Hove A\/S<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hove-as.com\/pt-pt\/contato\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contato - Hove A\/S\" \/>\n<meta property=\"og:description\" content=\"Contacte-nos Gratos pelo seu contacto! Por favor, forne\u00e7a as suas informa\u00e7\u00f5es e entraremos em contacto consigo.Quanto mais soubermos sobre o seu pedido, mais f\u00e1cil \u00e9 p\u00f4-lo em contacto com a pessoa certa ou dar-lhe a informa\u00e7\u00e3o correta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hove-as.com\/pt-pt\/contato\/\" \/>\n<meta property=\"og:site_name\" content=\"Hove A\/S\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-25T16:06:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hove-as.com\/wp-content\/uploads\/2022\/09\/hero-contact.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/contato\\\/\",\"url\":\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/contato\\\/\",\"name\":\"Contato - Hove A\\\/S\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/contato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/contato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hove-as.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/hero-contact.png\",\"datePublished\":\"2021-08-13T04:15:50+00:00\",\"dateModified\":\"2022-09-25T16:06:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/contato\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/contato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/contato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hove-as.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/hero-contact.png\",\"contentUrl\":\"https:\\\/\\\/hove-as.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/hero-contact.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/contato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/\",\"name\":\"Hove A\\\/S\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hove-as.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contato - Hove A\/S","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hove-as.com\/pt-pt\/contato\/","og_locale":"pt_PT","og_type":"article","og_title":"Contato - Hove A\/S","og_description":"Contacte-nos Gratos pelo seu contacto! Por favor, forne\u00e7a as suas informa\u00e7\u00f5es e entraremos em contacto consigo.Quanto mais soubermos sobre o seu pedido, mais f\u00e1cil \u00e9 p\u00f4-lo em contacto com a pessoa certa ou dar-lhe a informa\u00e7\u00e3o correta.","og_url":"https:\/\/hove-as.com\/pt-pt\/contato\/","og_site_name":"Hove A\/S","article_modified_time":"2022-09-25T16:06:38+00:00","og_image":[{"url":"https:\/\/hove-as.com\/wp-content\/uploads\/2022\/09\/hero-contact.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hove-as.com\/pt-pt\/contato\/","url":"https:\/\/hove-as.com\/pt-pt\/contato\/","name":"Contato - Hove A\/S","isPartOf":{"@id":"https:\/\/hove-as.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hove-as.com\/pt-pt\/contato\/#primaryimage"},"image":{"@id":"https:\/\/hove-as.com\/pt-pt\/contato\/#primaryimage"},"thumbnailUrl":"https:\/\/hove-as.com\/wp-content\/uploads\/2022\/09\/hero-contact.png","datePublished":"2021-08-13T04:15:50+00:00","dateModified":"2022-09-25T16:06:38+00:00","breadcrumb":{"@id":"https:\/\/hove-as.com\/pt-pt\/contato\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hove-as.com\/pt-pt\/contato\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hove-as.com\/pt-pt\/contato\/#primaryimage","url":"https:\/\/hove-as.com\/wp-content\/uploads\/2022\/09\/hero-contact.png","contentUrl":"https:\/\/hove-as.com\/wp-content\/uploads\/2022\/09\/hero-contact.png"},{"@type":"BreadcrumbList","@id":"https:\/\/hove-as.com\/pt-pt\/contato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hove-as.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Contato"}]},{"@type":"WebSite","@id":"https:\/\/hove-as.com\/pt-pt\/#website","url":"https:\/\/hove-as.com\/pt-pt\/","name":"Hove A\/S","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hove-as.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/hove-as.com\/pt-pt\/wp-json\/wp\/v2\/pages\/2265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hove-as.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hove-as.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hove-as.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hove-as.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=2265"}],"version-history":[{"count":0,"href":"https:\/\/hove-as.com\/pt-pt\/wp-json\/wp\/v2\/pages\/2265\/revisions"}],"wp:attachment":[{"href":"https:\/\/hove-as.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=2265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}